{"id":9,"count":3,"description":"","link":"https:\/\/cosmeticclinics.in\/blog\/category\/celebrity-news\/","name":"Celebrity News","slug":"celebrity-news","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Celebrity News Archives - Cosmetic Clinics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cosmeticclinics.in\/blog\/category\/celebrity-news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrity News Archives - Cosmetic Clinics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cosmeticclinics.in\/blog\/category\/celebrity-news\/\" \/>\n<meta property=\"og:site_name\" content=\"Cosmetic Clinics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebrity News Archives - Cosmetic Clinics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cosmeticclinics.in\/blog\/category\/celebrity-news\/","og_locale":"en_US","og_type":"article","og_title":"Celebrity News Archives - Cosmetic Clinics","og_url":"https:\/\/cosmeticclinics.in\/blog\/category\/celebrity-news\/","og_site_name":"Cosmetic Clinics","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cosmeticclinics.in\/blog\/category\/celebrity-news\/","url":"https:\/\/cosmeticclinics.in\/blog\/category\/celebrity-news\/","name":"Celebrity News Archives - Cosmetic Clinics","isPartOf":{"@id":"https:\/\/cosmeticclinics.in\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/cosmeticclinics.in\/blog\/category\/celebrity-news\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/cosmeticclinics.in\/blog\/category\/celebrity-news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cosmeticclinics.in\/blog\/"},{"@type":"ListItem","position":2,"name":"Celebrity News"}]},{"@type":"WebSite","@id":"https:\/\/cosmeticclinics.in\/blog\/#website","url":"https:\/\/cosmeticclinics.in\/blog\/","name":"Cosmetic Clinics","description":"","publisher":{"@id":"https:\/\/cosmeticclinics.in\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cosmeticclinics.in\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cosmeticclinics.in\/blog\/#organization","name":"Cosmetic Clinic","url":"https:\/\/cosmeticclinics.in\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cosmeticclinics.in\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/cosmeticclinics.in\/blog\/wp-content\/uploads\/2025\/05\/logo-1-e1747914773740.png","contentUrl":"https:\/\/cosmeticclinics.in\/blog\/wp-content\/uploads\/2025\/05\/logo-1-e1747914773740.png","width":1324,"height":1312,"caption":"Cosmetic Clinic"},"image":{"@id":"https:\/\/cosmeticclinics.in\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cosmeticclinics.in\/blog\/wp-json\/wp\/v2\/categories\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosmeticclinics.in\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/cosmeticclinics.in\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/cosmeticclinics.in\/blog\/wp-json\/wp\/v2\/posts?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}